{"id":7,"count":1,"description":"","link":"https:\/\/vallivaldesi.chiesavaldese.org\/pramollo\/category\/natale\/","name":"Natale","slug":"natale","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/vallivaldesi.chiesavaldese.org\/pramollo\/wp-json\/wp\/v2\/categories\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vallivaldesi.chiesavaldese.org\/pramollo\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/vallivaldesi.chiesavaldese.org\/pramollo\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/vallivaldesi.chiesavaldese.org\/pramollo\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}